{"id":145224,"date":"2024-10-28T18:58:30","date_gmt":"2024-10-28T17:58:30","guid":{"rendered":"https:\/\/rockers.de\/?post_type=product&#038;p=145224"},"modified":"2025-01-11T18:00:21","modified_gmt":"2025-01-11T17:00:21","slug":"rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl","status":"publish","type":"product","link":"https:\/\/rockers.de\/en\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/","title":{"rendered":"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl"},"content":{"rendered":"<p>Including Love In Space poster<\/p>","protected":false},"excerpt":{"rendered":"<p>Including Love In Space poster<\/p>","protected":false},"featured_media":145227,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[551,4577],"product_tag":[],"class_list":["post-145224","product","type-product","status-publish","has-post-thumbnail","product_cat-disco","product_cat-funk-soul","pa_att_artist-rene-riche-and-her-cosmic-band","pa_att_format-lp-vinyl","pa_att_genre-funk-soul","pa_att_jahr-144","pa_att_label-private-records-2","pa_att_land-germany","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl - Rockers Records<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rockers.de\/en\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl - Rockers Records\" \/>\n<meta property=\"og:description\" content=\"Including Love In Space poster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rockers.de\/en\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/\" \/>\n<meta property=\"og:site_name\" content=\"Rockers Records\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-11T17:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rockers.de\/wp-content\/uploads\/2024\/10\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1839\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/\",\"url\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/\",\"name\":\"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl - Rockers Records\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rockers.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rockers.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg\",\"datePublished\":\"2024-10-28T17:58:30+00:00\",\"dateModified\":\"2025-01-11T17:00:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rockers.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rockers.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg\",\"width\":1800,\"height\":1839,\"caption\":\"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rockers.de\\\/record\\\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rockers.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/rockers.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rockers.de\\\/#website\",\"url\":\"https:\\\/\\\/rockers.de\\\/\",\"name\":\"Rockers Records\",\"description\":\"Dein Schallplatten Store in Hannover\",\"publisher\":{\"@id\":\"https:\\\/\\\/rockers.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rockers.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rockers.de\\\/#organization\",\"name\":\"Rockers Records\",\"url\":\"https:\\\/\\\/rockers.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/rockers.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rockers.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Neue-Website-2022.jpg\",\"contentUrl\":\"https:\\\/\\\/rockers.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Neue-Website-2022.jpg\",\"width\":800,\"height\":800,\"caption\":\"Rockers Records\"},\"image\":{\"@id\":\"https:\\\/\\\/rockers.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl - Rockers Records","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rockers.de\/en\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/","og_locale":"en_US","og_type":"article","og_title":"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl - Rockers Records","og_description":"Including Love In Space poster","og_url":"https:\/\/rockers.de\/en\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/","og_site_name":"Rockers Records","article_modified_time":"2025-01-11T17:00:21+00:00","og_image":[{"width":1800,"height":1839,"url":"https:\/\/rockers.de\/wp-content\/uploads\/2024\/10\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/","url":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/","name":"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl - Rockers Records","isPartOf":{"@id":"https:\/\/rockers.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/#primaryimage"},"image":{"@id":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/#primaryimage"},"thumbnailUrl":"https:\/\/rockers.de\/wp-content\/uploads\/2024\/10\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg","datePublished":"2024-10-28T17:58:30+00:00","dateModified":"2025-01-11T17:00:21+00:00","breadcrumb":{"@id":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/#primaryimage","url":"https:\/\/rockers.de\/wp-content\/uploads\/2024\/10\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg","contentUrl":"https:\/\/rockers.de\/wp-content\/uploads\/2024\/10\/Rene-Riche-And-Her-Cosmic-Band-Love-In-Space-Reissue-LP-Vinyl-1.jpg","width":1800,"height":1839,"caption":"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl"},{"@type":"BreadcrumbList","@id":"https:\/\/rockers.de\/record\/rene-riche-and-her-cosmic-band-love-in-space-reissue-lp-vinyl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rockers.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/rockers.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Rene Riche And Her Cosmic Band-Love In Space Reissue-LP Vinyl"}]},{"@type":"WebSite","@id":"https:\/\/rockers.de\/#website","url":"https:\/\/rockers.de\/","name":"Rockers Records","description":"Your record store in Hanover","publisher":{"@id":"https:\/\/rockers.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rockers.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/rockers.de\/#organization","name":"Rockers Records","url":"https:\/\/rockers.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/rockers.de\/#\/schema\/logo\/image\/","url":"https:\/\/rockers.de\/wp-content\/uploads\/2022\/07\/Neue-Website-2022.jpg","contentUrl":"https:\/\/rockers.de\/wp-content\/uploads\/2022\/07\/Neue-Website-2022.jpg","width":800,"height":800,"caption":"Rockers Records"},"image":{"@id":"https:\/\/rockers.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/product\/145224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/media\/145227"}],"wp:attachment":[{"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/media?parent=145224"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/product_brand?post=145224"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/product_cat?post=145224"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rockers.de\/en\/wp-json\/wp\/v2\/product_tag?post=145224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}